{"id":25486,"date":"2024-09-18T20:49:27","date_gmt":"2024-09-18T20:49:27","guid":{"rendered":"https:\/\/co-travels.com\/%d1%82%d1%83%d1%80%d1%8b\/"},"modified":"2025-08-25T13:27:49","modified_gmt":"2025-08-25T13:27:49","slug":"%d1%82%d1%83%d1%80%d1%8b","status":"publish","type":"page","link":"https:\/\/co-travels.com\/ru\/%d1%82%d1%83%d1%80%d1%8b\/","title":{"rendered":"\u0422\u0443\u0440\u044b"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25486\" class=\"elementor elementor-25486 elementor-20320\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cb8b52 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"6cb8b52\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-83b0b70\" data-id=\"83b0b70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66e8191 title-alignment-left neuros-navigation-border-style-gradient elementor-invisible elementor-widget elementor-widget-neuros_services_listing\" data-id=\"66e8191\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_services_listing.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-service-listing-widget\">\n            <h2 class=\"neuros-heading heading-with-pagination\"><span class=\"neuros-heading-inner\"><span class=\"neuros-heading-content\">\u0411\u043e\u043b\u044c\u0448\u0435 \u0443\u0447\u0430\u0441\u0442\u043d\u0438\u043a\u043e\u0432 - \u041c\u0435\u043d\u044c\u0448\u0435 \u0446\u0435\u043d\u0430!<\/span><\/span><div class=\"owl-nav owl-nav-66e8191\"><\/div><\/h2>            \n            <div class=\"archive-listing\" data-ajax='{&quot;post_type&quot;:&quot;neuros_service&quot;,&quot;ignore_sticky_posts&quot;:true,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;asc&quot;,&quot;link_base&quot;:&quot;https:\\\/\\\/co-travels.com\\\/ru\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/25486\\\/&quot;,&quot;neuros_services_category&quot;:[&quot;slider&quot;],&quot;posts_per_page&quot;:-1}' data-widget='{&quot;listing_type&quot;:&quot;slider&quot;,&quot;item_class&quot;:&quot;service-item-wrapper&quot;,&quot;columns_number&quot;:4}'>\n                <div class=\"archive-listing-wrapper service-listing-wrapper service-slider-listing owl-carousel owl-theme\" data-slider-options={&quot;items&quot;:4,&quot;nav&quot;:true,&quot;dots&quot;:false,&quot;autoplayHoverPause&quot;:false,&quot;autoplay&quot;:false,&quot;autoplaySpeed&quot;:300,&quot;autoplayTimeout&quot;:5000,&quot;loop&quot;:false,&quot;speed&quot;:500,&quot;navContainer&quot;:&quot;.owl-nav-66e8191&quot;}>\n                    \n<div class=\"service-item-wrapper post-25731 neuros_service type-neuros_service status-publish has-post-thumbnail hentry neuros_services_category-148\">\n    <div class=\"service-item\">\n\n        <a class=\"service-item-link\" href=\"https:\/\/co-travels.com\/ru\/services\/%d1%83%d0%b4%d0%b8%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d0%bd%d1%8b%d0%b5-5-%d0%b4%d0%bd%d0%b5%d0%b9-%d0%b2-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d0%b5-%d0%ba%d1%83\/\"><img decoding=\"async\" alt=\"Darvaza 1\" srcset=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Darvaza-1-640x640.jpg 575w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Darvaza-1-640x640.jpg 991w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Darvaza-1-960x800.jpg 1340w\" sizes=\"(max-width: 575px) 575px, (max-width: 991px) 991px\" src=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Darvaza-1-960x800.jpg\" class=\"attachment-neuros_portfolio_grid_2_columns size-neuros_portfolio_grid_2_columns wp-post-image\" \/><\/a><div class=\"service-item-content\"><h5 class=\"service-post-title\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d1%83%d0%b4%d0%b8%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d0%bd%d1%8b%d0%b5-5-%d0%b4%d0%bd%d0%b5%d0%b9-%d0%b2-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d0%b5-%d0%ba%d1%83\/\">\u0412\u044b\u0445\u043e\u0434\u043d\u044b\u0435 \u0443 \u043a\u0440\u0430\u0442\u0435\u0440\u0430: \u041e\u0433\u043d\u0435\u043d\u043d\u043e\u0435 \u043f\u0440\u0438\u043a\u043b\u044e\u0447\u0435\u043d\u0438\u0435 \u0432 \u0414\u0430\u0440\u0432\u0430\u0437\u0435 (3 \u0434\u043d\u044f \/ 2 \u043d\u043e\u0447\u0438)<\/a><\/h5><\/div><div class=\"service-item-icon\"><div class=\"service-item-icon-wrapper\"><div class=\"service-item-icon-inner\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d1%83%d0%b4%d0%b8%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d0%bd%d1%8b%d0%b5-5-%d0%b4%d0%bd%d0%b5%d0%b9-%d0%b2-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d0%b5-%d0%ba%d1%83\/\" class=\"service-item-icon-link\"><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><\/a><\/div><\/div><\/div>\n    <\/div>\n<\/div>\n<div class=\"service-item-wrapper post-25727 neuros_service type-neuros_service status-publish has-post-thumbnail hentry neuros_services_category-148\">\n    <div class=\"service-item\">\n\n        <a class=\"service-item-link\" href=\"https:\/\/co-travels.com\/ru\/services\/%d1%83%d0%b4%d0%b8%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d0%bd%d1%8b%d0%b5-5-%d0%b4%d0%bd%d0%b5%d0%b9-%d0%b2-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d0%b5-%d0%b8%d1%81\/\"><img decoding=\"async\" alt=\"Kunya urgench\" srcset=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Kunya-urgench.jpg 575w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Kunya-urgench.jpg 991w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Kunya-urgench.jpg 1340w\" sizes=\"(max-width: 575px) 575px, (max-width: 991px) 991px\" src=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Kunya-urgench.jpg\" class=\"attachment-neuros_portfolio_grid_2_columns size-neuros_portfolio_grid_2_columns wp-post-image\" \/><\/a><div class=\"service-item-content\"><h5 class=\"service-post-title\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d1%83%d0%b4%d0%b8%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d0%bd%d1%8b%d0%b5-5-%d0%b4%d0%bd%d0%b5%d0%b9-%d0%b2-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d0%b5-%d0%b8%d1%81\/\">\u0422\u0443\u0440 \u00ab\u0412\u0435\u043b\u0438\u043a\u0438\u0439 \u0428\u0451\u043b\u043a\u043e\u0432\u044b\u0439 \u043f\u0443\u0442\u044c\u00bb \u2014 5 \u0434\u043d\u0435\u0439 \/ 4 \u043d\u043e\u0447\u0438<\/a><\/h5><\/div><div class=\"service-item-icon\"><div class=\"service-item-icon-wrapper\"><div class=\"service-item-icon-inner\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d1%83%d0%b4%d0%b8%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d0%bd%d1%8b%d0%b5-5-%d0%b4%d0%bd%d0%b5%d0%b9-%d0%b2-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d0%b5-%d0%b8%d1%81\/\" class=\"service-item-icon-link\"><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><\/a><\/div><\/div><\/div>\n    <\/div>\n<\/div>\n<div class=\"service-item-wrapper post-25723 neuros_service type-neuros_service status-publish has-post-thumbnail hentry neuros_services_category-148\">\n    <div class=\"service-item\">\n\n        <a class=\"service-item-link\" href=\"https:\/\/co-travels.com\/ru\/services\/%d0%ba%d0%b0%d0%bd%d1%83%d0%bd-%d0%bd%d0%be%d0%b2%d0%be%d0%b3%d0%be-%d0%b3%d0%be%d0%b4%d0%b0-%d0%b2-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d0%b5\/\"><img decoding=\"async\" alt=\"70772407-Ashgabat-Turkmenistan-Central-Asia-Asia-architecture-avenue-city-colourful-golden-independence-monument-park\" srcset=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/70772407-Ashgabat-Turkmenistan-Central-Asia-Asia-architecture-avenue-city-colourful-golden-independence-monument-park-640x640.jpg 575w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/70772407-Ashgabat-Turkmenistan-Central-Asia-Asia-architecture-avenue-city-colourful-golden-independence-monument-park-640x640.jpg 991w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/70772407-Ashgabat-Turkmenistan-Central-Asia-Asia-architecture-avenue-city-colourful-golden-independence-monument-park-960x744.jpg 1340w\" sizes=\"(max-width: 575px) 575px, (max-width: 991px) 991px\" src=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/70772407-Ashgabat-Turkmenistan-Central-Asia-Asia-architecture-avenue-city-colourful-golden-independence-monument-park-960x744.jpg\" class=\"attachment-neuros_portfolio_grid_2_columns size-neuros_portfolio_grid_2_columns wp-post-image\" \/><\/a><div class=\"service-item-content\"><h5 class=\"service-post-title\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d0%ba%d0%b0%d0%bd%d1%83%d0%bd-%d0%bd%d0%be%d0%b2%d0%be%d0%b3%d0%be-%d0%b3%d0%be%d0%b4%d0%b0-%d0%b2-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d0%b5\/\">\u041f\u0443\u0442\u0435\u0448\u0435\u0441\u0442\u0432\u0438\u0435 \u043f\u043e \u0422\u0443\u0440\u043a\u043c\u0435\u043d\u0438\u0441\u0442\u0430\u043d\u0443 7 \u0434\u043d\u0435\u0439 \/ 6 \u043d\u043e\u0447\u0435\u0439<\/a><\/h5><\/div><div class=\"service-item-icon\"><div class=\"service-item-icon-wrapper\"><div class=\"service-item-icon-inner\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d0%ba%d0%b0%d0%bd%d1%83%d0%bd-%d0%bd%d0%be%d0%b2%d0%be%d0%b3%d0%be-%d0%b3%d0%be%d0%b4%d0%b0-%d0%b2-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d0%b5\/\" class=\"service-item-icon-link\"><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><\/a><\/div><\/div><\/div>\n    <\/div>\n<\/div>\n<div class=\"service-item-wrapper post-25717 neuros_service type-neuros_service status-publish has-post-thumbnail hentry neuros_services_category-148\">\n    <div class=\"service-item\">\n\n        <a class=\"service-item-link\" href=\"https:\/\/co-travels.com\/ru\/services\/%d0%b3%d1%80%d1%83%d0%bf%d0%bf%d0%be%d0%b2%d0%b0%d1%8f-%d0%bf%d0%be%d0%b5%d0%b7%d0%b4%d0%ba%d0%b0-%d0%bf%d0%be-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d1%83\/\"><img decoding=\"async\" alt=\"Ashgabat\" srcset=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Ashgabat-640x640.jpg 575w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Ashgabat-640x640.jpg 991w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Ashgabat-960x960.jpg 1340w\" sizes=\"(max-width: 575px) 575px, (max-width: 991px) 991px\" src=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/Ashgabat-960x960.jpg\" class=\"attachment-neuros_portfolio_grid_2_columns size-neuros_portfolio_grid_2_columns wp-post-image\" \/><\/a><div class=\"service-item-content\"><h5 class=\"service-post-title\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d0%b3%d1%80%d1%83%d0%bf%d0%bf%d0%be%d0%b2%d0%b0%d1%8f-%d0%bf%d0%be%d0%b5%d0%b7%d0%b4%d0%ba%d0%b0-%d0%bf%d0%be-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d1%83\/\">\u041a\u043b\u0430\u0441\u0441\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u0442\u0443\u0440 8 \u0434\u043d\u0435\u0439\/ 7 \u043d\u043e\u0447\u0435\u0439 \u0432 \u0422\u0443\u0440\u043a\u043c\u0435\u043d\u0438\u0441\u0442\u0430\u043d\u0435.<\/a><\/h5><\/div><div class=\"service-item-icon\"><div class=\"service-item-icon-wrapper\"><div class=\"service-item-icon-inner\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d0%b3%d1%80%d1%83%d0%bf%d0%bf%d0%be%d0%b2%d0%b0%d1%8f-%d0%bf%d0%be%d0%b5%d0%b7%d0%b4%d0%ba%d0%b0-%d0%bf%d0%be-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd%d1%83\/\" class=\"service-item-icon-link\"><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><\/a><\/div><\/div><\/div>\n    <\/div>\n<\/div>\n<div class=\"service-item-wrapper post-25715 neuros_service type-neuros_service status-publish has-post-thumbnail hentry neuros_services_category-148\">\n    <div class=\"service-item\">\n\n        <a class=\"service-item-link\" href=\"https:\/\/co-travels.com\/ru\/services\/%d1%83%d0%b4%d0%b8%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d0%bd%d1%8b%d0%b9-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd\/\"><img decoding=\"async\" alt=\"WhatsApp Image 2025-07-25 at 11.21.57\" srcset=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2025-07-25-at-11.21.57-640x640.jpeg 575w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2025-07-25-at-11.21.57-640x640.jpeg 991w, https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2025-07-25-at-11.21.57-960x750.jpeg 1340w\" sizes=\"(max-width: 575px) 575px, (max-width: 991px) 991px\" src=\"https:\/\/co-travels.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2025-07-25-at-11.21.57-960x750.jpeg\" class=\"attachment-neuros_portfolio_grid_2_columns size-neuros_portfolio_grid_2_columns wp-post-image\" \/><\/a><div class=\"service-item-content\"><h5 class=\"service-post-title\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d1%83%d0%b4%d0%b8%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d0%bd%d1%8b%d0%b9-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd\/\">\u041f\u0443\u0442\u0435\u0448\u0435\u0441\u0442\u0432\u0438\u0435 \u043f\u043e \u0422\u0443\u0440\u043a\u043c\u0435\u0438\u0441\u0442\u0430\u043d\u0443 10 \u0434\u043d\u0435\u0439 \/ 9 \u043d\u043e\u0447\u0435\u0439<\/a><\/h5><\/div><div class=\"service-item-icon\"><div class=\"service-item-icon-wrapper\"><div class=\"service-item-icon-inner\"><a href=\"https:\/\/co-travels.com\/ru\/services\/%d1%83%d0%b4%d0%b8%d0%b2%d0%b8%d1%82%d0%b5%d0%bb%d1%8c%d0%bd%d1%8b%d0%b9-%d1%82%d1%83%d1%80%d0%ba%d0%bc%d0%b5%d0%bd%d0%b8%d1%81%d1%82%d0%b0%d0%bd\/\" class=\"service-item-icon-link\"><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><i aria-hidden=\"true\" class=\"fontello icon-button-arrow\"><\/i><\/a><\/div><\/div><\/div>\n    <\/div>\n<\/div>                <\/div>\n\n                            <\/div>\n\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f404ac3 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f404ac3\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a29529\" data-id=\"2a29529\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c74ad83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c74ad83\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3dc19ba\" data-id=\"3dc19ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03ea95f elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"03ea95f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">\u041c\u044b \u0432\u0441\u0435\u0433\u0434\u0430 \u0433\u043e\u0442\u043e\u0432\u044b \u043f\u043e\u043c\u043e\u0447\u044c \u0432\u0430\u043c \u0438 \u043e\u0442\u0432\u0435\u0442\u0438\u0442\u044c \u043d\u0430 \u0432\u0430\u0448\u0438 \u0432\u043e\u043f\u0440\u043e\u0441\u044b<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b461ee elementor-widget elementor-widget-text-editor\" data-id=\"4b461ee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0415\u0441\u043b\u0438 \u0443 \u0432\u0430\u0441 \u0435\u0441\u0442\u044c \u0432\u043e\u043f\u0440\u043e\u0441\u044b, \u0438\u0434\u0435\u0438 \u0438\u043b\u0438 \u043f\u0440\u0435\u0434\u043b\u043e\u0436\u0435\u043d\u0438\u044f, \u0432\u044b \u043c\u043e\u0436\u0435\u0442\u0435 \u0441\u0432\u044f\u0437\u0430\u0442\u044c\u0441\u044f \u0441 \u043d\u0430\u0448\u0435\u0439 \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0435\u0439.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8665f2 elementor-widget__width-initial elementor-widget elementor-widget-neuros_heading\" data-id=\"d8665f2\" data-element_type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">WhatsApp \u043d\u043e\u043c\u0435\u0440:<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1549270 elementor-widget__width-initial elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-widget elementor-widget-text-editor\" data-id=\"1549270\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"tel:+99365216509\">+(993) 65400420<\/a><\/p><p><a href=\"tel:+99365216510\">+(993) 63459922<\/a><\/p><p><a href=\"tel:+99365216510\">+(993) 65504341<\/a><\/p><p><a href=\"tel:+99365216510\">+(993) 62937557<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f3f0aa elementor-widget__width-initial elementor-widget elementor-widget-neuros_heading\" data-id=\"9f3f0aa\" data-element_type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">\u041d\u0430\u0448 \u0430\u0434\u0440\u0435\u0441:<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46101f9 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"46101f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"tel:+99365216509\">+(993) 65400420<\/a><\/p><p><a href=\"tel:+99365216510\">+(993) 63459922<\/a><\/p><p><a href=\"tel:+99365216510\">+(993) 65504341<\/a><\/p><p><a href=\"tel:+99365216510\">+(993) 62937557<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cf5f7c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3cf5f7c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0422\u0443\u0440\u043a\u043c\u0435\u043d\u0438\u0441\u0442\u0430\u043d, \u0433\u043e\u0440\u043e\u0434 \u0410\u0448\u0445\u0430\u0431\u0430\u0434,<\/p><p>\u043f\u0440\u043e\u0441\u043f\u0435\u043a\u0442 \u0411\u0438\u0442\u0430\u0440\u0430\u043f \u0422\u0443\u0440\u043a\u043c\u0435\u043d\u0438\u0441\u0442\u0430\u043d,<\/p><p>\u0437\u0434\u0430\u043d\u0438\u0435 \u0410\u043a-\u041c\u0430\u0439\u044f, \u043e\u0444\u0438\u0441 &#8212; 94<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea18992 elementor-widget__width-initial elementor-widget elementor-widget-neuros_heading\" data-id=\"ea18992\" data-element_type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">\u042d\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u0430\u044f \u043f\u043e\u0447\u0442\u0430<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61a3fd6 elementor-widget__width-initial elementor-widget elementor-widget-neuros_heading\" data-id=\"61a3fd6\" data-element_type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">\u041d\u0430\u0448 \u043d\u043e\u043c\u0435\u0440 \u0442\u0435\u043b\u0435\u0444\u043e\u043d\u0430:<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a836084 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"a836084\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"mailto:contact@co-travels.com\">contact@co-travels.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03b4339 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"03b4339\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>+993-12-21-65-09<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03a7e75 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"03a7e75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"block-26\" class=\"widget side-widget widget_block\"><div class=\"widget-wrapper side-widget-wrapper\"><div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><p><a href=\"mailto:director@co-travels.com\">director@co-travels.com<\/a><\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d0f707 elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"3d0f707\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5fb57d elementor-widget__width-initial elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"d5fb57d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>maksat@co-travels.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9530faf elementor-widget elementor-widget-neuros_heading\" data-id=\"9530faf\" data-element_type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h6 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">\u0421\u043e\u0446\u0438\u0430\u043b\u044c\u043d\u044b\u0435 \u0441\u0435\u0442\u0438<\/span><\/h6><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5142a4e elementor-shape-square e-grid-align-left elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"5142a4e\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-af284db\" href=\"https:\/\/www.facebook.com\/share\/1AbfR2drCs\/?mibextid=wwXIfr\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-aaa4c39\" href=\"https:\/\/twitter.com\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-ce51307\" href=\"https:\/\/www.instagram.com\/co.travels.tm\/#\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-9926db3\" href=\"https:\/\/www.youtube.com\/@cotravelstm\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tiktok elementor-repeater-item-4e690c5\" href=\"https:\/\/tiktok.com\/@co.travels.tm\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tiktok<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-tiktok\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-527f0d6\" data-id=\"527f0d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8117dd0 wpforms-button-border-style-solid wpforms-button-bakground-style-solid elementor-widget elementor-widget-neuros_wpforms\" data-id=\"8117dd0\" data-element_type=\"widget\" data-widget_type=\"neuros_wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"neuros-wpforms-widget\">\n            <h4 class=\"wpforms-widget-heading neuros-heading\"><span class=\"neuros-heading-content\">\u0421\u0432\u044f\u0437\u0430\u0442\u044c\u0441\u044f \u0441 \u043d\u0430\u043c\u0438<\/span><\/h4><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-22894\"><form id=\"wpforms-form-22894\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"22894\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/ru\/wp-json\/wp\/v2\/pages\/25486\" data-token=\"ae050e661bb1d5e8db535c72ee3dbb2c\" data-token-time=\"1788340469\"><div class=\"wpforms-head-container\"><div class=\"wpforms-description\">\u0415\u0441\u0442\u044c \u0432\u043e\u043f\u0440\u043e\u0441\u044b? \u041c\u044b \u0437\u0434\u0435\u0441\u044c, \u0447\u0442\u043e\u0431\u044b \u043f\u043e\u043c\u043e\u0447\u044c! <\/div><\/div><noscript class=\"wpforms-error-noscript\">\u0414\u043b\u044f \u0437\u0430\u043f\u043e\u043b\u043d\u0435\u043d\u0438\u044f \u0434\u0430\u043d\u043d\u043e\u0439 \u0444\u043e\u0440\u043c\u044b \u0432\u043a\u043b\u044e\u0447\u0438\u0442\u0435 JavaScript \u0432 \u0431\u0440\u0430\u0443\u0437\u0435\u0440\u0435.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">\u0414\u043b\u044f \u0437\u0430\u043f\u043e\u043b\u043d\u0435\u043d\u0438\u044f \u0434\u0430\u043d\u043d\u043e\u0439 \u0444\u043e\u0440\u043c\u044b \u0432\u043a\u043b\u044e\u0447\u0438\u0442\u0435 JavaScript \u0432 \u0431\u0440\u0430\u0443\u0437\u0435\u0440\u0435.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-22894-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-22894-field_1\" aria-hidden=\"false\">\u041f\u043e\u043b\u043d\u043e\u0435 \u0438\u043c\u044f <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-22894-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"\u041f\u043e\u043b\u043d\u043e\u0435 \u0438\u043c\u044f\" aria-errormessage=\"wpforms-22894-field_1-error\" required><\/div><div id=\"wpforms-22894-field_3-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-22894-field_3\" aria-hidden=\"false\">\u042d\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u0430\u044f \u043f\u043e\u0447\u0442\u0430 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-22894-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"\u042d\u043b\u0435\u043a\u0442\u0440\u043e\u043d\u043d\u0430\u044f \u043f\u043e\u0447\u0442\u0430\" spellcheck=\"false\" aria-errormessage=\"wpforms-22894-field_3-error\" required><\/div><div id=\"wpforms-22894-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-22894-field_4\" aria-hidden=\"false\">\u0422\u0435\u043c\u0430 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-22894-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"\u0422\u0435\u043c\u0430\" aria-errormessage=\"wpforms-22894-field_4-error\" required><\/div><div id=\"wpforms-22894-field_5-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-22894-field_5\" aria-hidden=\"false\">\u0421\u043e\u043e\u0431\u0449\u0435\u043d\u0438\u0435<\/label><textarea id=\"wpforms-22894-field_5\" class=\"wpforms-field-small\" name=\"wpforms[fields][5]\" placeholder=\"\u0421\u043e\u043e\u0431\u0449\u0435\u043d\u0438\u0435\" aria-errormessage=\"wpforms-22894-field_5-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"22894\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/co-travels.com\/ru\/wp-json\/wp\/v2\/pages\/25486\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-22894\" class=\"wpforms-submit\" data-alt-text=\"\u041e\u0442\u043f\u0440\u0430\u0432\u043a\u0430...\" data-submit-text=\"\u041e\u0442\u043f\u0440\u0430\u0432\u0438\u0442\u044c \u0441\u043e\u043e\u0431\u0449\u0435\u043d\u0438\u0435\" aria-live=\"assertive\" value=\"wpforms-submit\">\u041e\u0442\u043f\u0440\u0430\u0432\u0438\u0442\u044c \u0441\u043e\u043e\u0431\u0449\u0435\u043d\u0438\u0435<\/button><img decoding=\"async\" src=\"https:\/\/co-travels.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\u0417\u0430\u0433\u0440\u0443\u0437\u043a\u0430\"><\/div><\/form><\/div>  <!-- .wpforms-container -->        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0415\u0441\u043b\u0438 \u0443 \u0432\u0430\u0441 \u0435\u0441\u0442\u044c \u0432\u043e\u043f\u0440\u043e\u0441\u044b, \u0438\u0434\u0435\u0438 \u0438\u043b\u0438 \u043f\u0440\u0435\u0434\u043b\u043e\u0436\u0435\u043d\u0438\u044f, \u0432\u044b \u043c\u043e\u0436\u0435\u0442\u0435 \u0441\u0432\u044f\u0437\u0430\u0442\u044c\u0441\u044f \u0441 \u043d\u0430\u0448\u0435\u0439 \u043a\u043e\u043c\u043f\u0430\u043d\u0438\u0435\u0439. +(993) 65400420 +(993) 63459922 +(993) 65504341 +(993) 62937557 +(993) 65400420 +(993) 63459922 +(993) 65504341 +(993) 62937557 \u0422\u0443\u0440\u043a\u043c\u0435\u043d\u0438\u0441\u0442\u0430\u043d, \u0433\u043e\u0440\u043e\u0434 \u0410\u0448\u0445\u0430\u0431\u0430\u0434, \u043f\u0440\u043e\u0441\u043f\u0435\u043a\u0442 \u0411\u0438\u0442\u0430\u0440\u0430\u043f \u0422\u0443\u0440\u043a\u043c\u0435\u043d\u0438\u0441\u0442\u0430\u043d, \u0437\u0434\u0430\u043d\u0438\u0435 \u0410\u043a-\u041c\u0430\u0439\u044f, \u043e\u0444\u0438\u0441 &#8212; 94&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25486","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/co-travels.com\/ru\/wp-json\/wp\/v2\/pages\/25486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/co-travels.com\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/co-travels.com\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/co-travels.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/co-travels.com\/ru\/wp-json\/wp\/v2\/comments?post=25486"}],"version-history":[{"count":14,"href":"https:\/\/co-travels.com\/ru\/wp-json\/wp\/v2\/pages\/25486\/revisions"}],"predecessor-version":[{"id":31488,"href":"https:\/\/co-travels.com\/ru\/wp-json\/wp\/v2\/pages\/25486\/revisions\/31488"}],"wp:attachment":[{"href":"https:\/\/co-travels.com\/ru\/wp-json\/wp\/v2\/media?parent=25486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}